{"id":1,"count":2,"description":"","link":"https:\/\/styleinterieur.blog\/en\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/styleinterieur.blog\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/styleinterieur.blog\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/styleinterieur.blog\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/styleinterieur.blog\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}